{"id":7366,"date":"2026-03-23T09:56:43","date_gmt":"2026-03-23T08:56:43","guid":{"rendered":"https:\/\/www.bernabohomegallery.it\/?post_type=fw-portfolio&#038;p=7366"},"modified":"2026-03-23T09:59:02","modified_gmt":"2026-03-23T08:59:02","slug":"scontro-di-situazioni","status":"publish","type":"fw-portfolio","link":"https:\/\/www.bernabohomegallery.it\/en\/opere\/scontro-di-situazioni\/","title":{"rendered":"Scontro di situazioni"},"content":{"rendered":"<div id=\"thz-section-holder-s8b4506e5\" class=\"thz-section-holder section-notcontained none\" data-view-brightness=\"none\">\n\t<section class=\"thz-section\">\n\t\t<div class=\"thz-section-in\">\n\t\t\t\t\t<div class=\"thz-container content-notcontained\">\n\t\t\t\t<div class=\"thz-row\">\n\t<div id=\"thz-column-ce2040649\" class=\"thz-column thz-col-1 fstart\">\n\t<div class=\"thz-column-container\">\n        <div class=\"thz-column-in\">\n                        <div class=\"thz-column-shortcodes\">\t\n                <div id=\"thz-text-block-7cf2af34\" class=\"thz-shc thz-text-block\"><p>A blend of energetic lines and sharp contrasts creates a composition with a strong visual impact. Emilio Vedova transforms black and white into a field of tension, where gesture and matter collide in a dynamic and powerful balance.<span class=\"Apple-converted-space\">\u00a0\u00a0<\/span>The layering of brushstrokes and crossed marks conveys all the intensity of his informal research, full of energy and movement.<span class=\"Apple-converted-space\">\u00a0\u00a0<\/span>A vibrant and material work, among the most representative of the artist's expressive power.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p><p>To receive more information about the artwork for sale we are available by phone and email\u00a0<a href=\"mailto:info@bernabohomegallery.it\">info@bernabohomegallery.it<\/a><\/p><\/div>            <\/div>\n                                            <\/div>\n    <\/div>\n<\/div><\/div>\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Un intreccio di segni energici e contrasti netti costruisce una composizione di forte impatto visivo. Emilio Vedova trasforma il bianco e nero in un campo di tensione, dove gesto e materia si scontrano in un equilibrio dinamico e potente.\u00a0\u00a0La stratificazione di pennellate e segni incrociati restituisce tutta l\u2019intensit\u00e0 della sua ricerca informale, carica di energia e movimento.\u00a0\u00a0Un\u2019opera vibrante e materica, tra le pi\u00f9 rappresentative della forza espressiva dell\u2019artista.\u00a0Per ricevere maggiori informazioni sull&#8217;opera d&#8217;arte in vendita\u00a0siamo disponibili telefonicamente e alla mail\u00a0info@bernabohomegallery.it<\/p>","protected":false},"author":3,"featured_media":7367,"template":"","class_list":["post-7366","fw-portfolio","type-fw-portfolio","status-publish","has-post-thumbnail","hentry","fw-portfolio-category-modern","fw-portfolio-tag-emilio-vedova"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Scontro di situazioni - Emilio Vedova - Bernab\u00f2 Home Gallery<\/title>\n<meta name=\"description\" content=\"Acquista l&#039;esclusiva opera Scontro di situazioni di Emilio Vedova. Pezzo unico in esclusiva da Bernab\u00f2 Home Gallery.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bernabohomegallery.it\/en\/artworks\/scontro-di-situazioni\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scontro di situazioni - Emilio Vedova - Bernab\u00f2 Home Gallery\" \/>\n<meta property=\"og:description\" content=\"Acquista l&#039;esclusiva opera Scontro di situazioni di Emilio Vedova. Pezzo unico in esclusiva da Bernab\u00f2 Home Gallery.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bernabohomegallery.it\/en\/artworks\/scontro-di-situazioni\/\" \/>\n<meta property=\"og:site_name\" content=\"Bernab\u00f2 Home Gallery\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Bernabohomegallery\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T08:59:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bernabohomegallery.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-20-at-15.54.45.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1397\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bernabohomegallery.it\/opere\/scontro-di-situazioni\/\",\"url\":\"https:\/\/www.bernabohomegallery.it\/opere\/scontro-di-situazioni\/\",\"name\":\"Scontro di situazioni - Emilio Vedova - Bernab\u00f2 Home Gallery\",\"isPartOf\":{\"@id\":\"https:\/\/www.bernabohomegallery.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bernabohomegallery.it\/opere\/scontro-di-situazioni\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.bernabohomegallery.it\/opere\/scontro-di-situazioni\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bernabohomegallery.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-20-at-15.54.45.jpeg\",\"datePublished\":\"2026-03-23T08:56:43+00:00\",\"dateModified\":\"2026-03-23T08:59:02+00:00\",\"description\":\"Acquista l'esclusiva opera Scontro di situazioni di Emilio Vedova. Pezzo unico in esclusiva da Bernab\u00f2 Home Gallery.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bernabohomegallery.it\/opere\/scontro-di-situazioni\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bernabohomegallery.it\/opere\/scontro-di-situazioni\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.bernabohomegallery.it\/opere\/scontro-di-situazioni\/#primaryimage\",\"url\":\"https:\/\/www.bernabohomegallery.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-20-at-15.54.45.jpeg\",\"contentUrl\":\"https:\/\/www.bernabohomegallery.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-20-at-15.54.45.jpeg\",\"width\":2048,\"height\":1397},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bernabohomegallery.it\/opere\/scontro-di-situazioni\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.bernabohomegallery.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\/\/www.bernabohomegallery.it\/opere\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Scontro di situazioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bernabohomegallery.it\/#website\",\"url\":\"https:\/\/www.bernabohomegallery.it\/\",\"name\":\"Bernab\u00f2 Home Gallery\",\"description\":\"Galleria arte moderna e contemporanea\",\"publisher\":{\"@id\":\"https:\/\/www.bernabohomegallery.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bernabohomegallery.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bernabohomegallery.it\/#organization\",\"name\":\"Bernab\u00f2 Home Gallery\",\"url\":\"https:\/\/www.bernabohomegallery.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.bernabohomegallery.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bernabohomegallery.it\/wp-content\/uploads\/2024\/04\/bernabo_logo.png\",\"contentUrl\":\"https:\/\/www.bernabohomegallery.it\/wp-content\/uploads\/2024\/04\/bernabo_logo.png\",\"width\":600,\"height\":249,\"caption\":\"Bernab\u00f2 Home Gallery\"},\"image\":{\"@id\":\"https:\/\/www.bernabohomegallery.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Bernabohomegallery\",\"https:\/\/www.instagram.com\/bernabohomegallery\/\",\"https:\/\/www.linkedin.com\/company\/bernab-home-gallery\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scontro di situazioni - Emilio Vedova - Bernab\u00f2 Home Gallery","description":"Acquista l'esclusiva opera Scontro di situazioni di Emilio Vedova. Pezzo unico in esclusiva da Bernab\u00f2 Home Gallery.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bernabohomegallery.it\/en\/artworks\/scontro-di-situazioni\/","og_locale":"en_US","og_type":"article","og_title":"Scontro di situazioni - Emilio Vedova - Bernab\u00f2 Home Gallery","og_description":"Acquista l'esclusiva opera Scontro di situazioni di Emilio Vedova. Pezzo unico in esclusiva da Bernab\u00f2 Home Gallery.","og_url":"https:\/\/www.bernabohomegallery.it\/en\/artworks\/scontro-di-situazioni\/","og_site_name":"Bernab\u00f2 Home Gallery","article_publisher":"https:\/\/www.facebook.com\/Bernabohomegallery","article_modified_time":"2026-03-23T08:59:02+00:00","og_image":[{"width":2048,"height":1397,"url":"https:\/\/www.bernabohomegallery.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-20-at-15.54.45.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bernabohomegallery.it\/opere\/scontro-di-situazioni\/","url":"https:\/\/www.bernabohomegallery.it\/opere\/scontro-di-situazioni\/","name":"Scontro di situazioni - Emilio Vedova - Bernab\u00f2 Home Gallery","isPartOf":{"@id":"https:\/\/www.bernabohomegallery.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bernabohomegallery.it\/opere\/scontro-di-situazioni\/#primaryimage"},"image":{"@id":"https:\/\/www.bernabohomegallery.it\/opere\/scontro-di-situazioni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bernabohomegallery.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-20-at-15.54.45.jpeg","datePublished":"2026-03-23T08:56:43+00:00","dateModified":"2026-03-23T08:59:02+00:00","description":"Acquista l'esclusiva opera Scontro di situazioni di Emilio Vedova. Pezzo unico in esclusiva da Bernab\u00f2 Home Gallery.","breadcrumb":{"@id":"https:\/\/www.bernabohomegallery.it\/opere\/scontro-di-situazioni\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bernabohomegallery.it\/opere\/scontro-di-situazioni\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bernabohomegallery.it\/opere\/scontro-di-situazioni\/#primaryimage","url":"https:\/\/www.bernabohomegallery.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-20-at-15.54.45.jpeg","contentUrl":"https:\/\/www.bernabohomegallery.it\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-20-at-15.54.45.jpeg","width":2048,"height":1397},{"@type":"BreadcrumbList","@id":"https:\/\/www.bernabohomegallery.it\/opere\/scontro-di-situazioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bernabohomegallery.it\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/www.bernabohomegallery.it\/opere\/"},{"@type":"ListItem","position":3,"name":"Scontro di situazioni"}]},{"@type":"WebSite","@id":"https:\/\/www.bernabohomegallery.it\/#website","url":"https:\/\/www.bernabohomegallery.it\/","name":"Bernab\u00f2 Home Gallery","description":"Galleria arte moderna e contemporanea","publisher":{"@id":"https:\/\/www.bernabohomegallery.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bernabohomegallery.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.bernabohomegallery.it\/#organization","name":"Bernab\u00f2 Home Gallery","url":"https:\/\/www.bernabohomegallery.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bernabohomegallery.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.bernabohomegallery.it\/wp-content\/uploads\/2024\/04\/bernabo_logo.png","contentUrl":"https:\/\/www.bernabohomegallery.it\/wp-content\/uploads\/2024\/04\/bernabo_logo.png","width":600,"height":249,"caption":"Bernab\u00f2 Home Gallery"},"image":{"@id":"https:\/\/www.bernabohomegallery.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Bernabohomegallery","https:\/\/www.instagram.com\/bernabohomegallery\/","https:\/\/www.linkedin.com\/company\/bernab-home-gallery\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.bernabohomegallery.it\/en\/wp-json\/wp\/v2\/fw-portfolio\/7366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bernabohomegallery.it\/en\/wp-json\/wp\/v2\/fw-portfolio"}],"about":[{"href":"https:\/\/www.bernabohomegallery.it\/en\/wp-json\/wp\/v2\/types\/fw-portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.bernabohomegallery.it\/en\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":3,"href":"https:\/\/www.bernabohomegallery.it\/en\/wp-json\/wp\/v2\/fw-portfolio\/7366\/revisions"}],"predecessor-version":[{"id":7370,"href":"https:\/\/www.bernabohomegallery.it\/en\/wp-json\/wp\/v2\/fw-portfolio\/7366\/revisions\/7370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bernabohomegallery.it\/en\/wp-json\/wp\/v2\/media\/7367"}],"wp:attachment":[{"href":"https:\/\/www.bernabohomegallery.it\/en\/wp-json\/wp\/v2\/media?parent=7366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}